{"id":19256,"date":"2024-11-15T17:24:44","date_gmt":"2024-11-15T16:24:44","guid":{"rendered":"https:\/\/www.groupeguillin.fr\/?page_id=19256"},"modified":"2025-06-25T17:31:24","modified_gmt":"2025-06-25T15:31:24","slug":"sharptek","status":"publish","type":"page","link":"https:\/\/www.groupeguillin.fr\/it\/sharptek\/","title":{"rendered":"Sharptek"},"content":{"rendered":"<p><div class=\"et_d4_element et_pb_section et_pb_section_0  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_0 et_pb_equal_columns  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_0  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_0  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_section et_pb_section_1 et_pb_with_background  et_pb_css_mix_blend_mode et_section_regular section_has_divider et_pb_bottom_divider et_pb_top_divider et_block_section\" >\n\t\t\t\t<div class=\"et_pb_top_inside_divider et-no-transition\"><\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_1 et_pb_equal_columns  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_1  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_image et_pb_image_0\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<span class=\"et_pb_image_wrap \"><img decoding=\"async\" width=\"748\" height=\"214\" src=\"https:\/\/www.groupeguillin.fr\/wp-content\/uploads\/2024\/10\/sharptek-logo-blanc-2.png\" alt=\"\" title=\"sharptek logo blanc\" class=\"wp-image-18823\" \/><\/span>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element dsm_block_reveal_text dsm_block_reveal_text_0\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"dsm_block_reveal_text_wrapper\" data-dsm-block-reveal-text=[{\"animation\":\"lr\",\"color\":\"#FFFFFF\",\"delay\":\"0.1\",\"viewport\":\"80%\"}]><h2 class=\"dsm_block_reveal_text_header et_pb_module_header\">MENO IMBALLAGGIO, PI\u00da PROTEZIONE<\/h2><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_1 et_animated  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h3 style=\"color: #ffffff; line-height: 32px; text-align: left;\">Presentiamo <span class=\"underline\">SharpTek:<\/span> la <span class=\"underline\">tecnologia<\/span> innovativa che offre un vassoio completamente riciclabile, <span class=\"underline\">senza pad<\/span>, riducendo il peso dell'imballaggio del 17% e rivoluzionando <span class=\"underline\">la protezione dei piccoli frutti delicati!<\/span><\/h3><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_image et_pb_image_1\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<span class=\"et_pb_image_wrap \"><img decoding=\"async\" width=\"2303\" height=\"2303\" src=\"https:\/\/www.groupeguillin.fr\/wp-content\/uploads\/2024\/10\/ZOOM-SHARPTEK-FRAMBOISES-rvb.png\" alt=\"\" title=\"ZOOM SHARPTEK FRAMBOISES rvb\" class=\"wp-image-18830\" \/><\/span>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_row et_pb_row_2 et_pb_equal_columns  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_2  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element dsm_block_reveal_text dsm_block_reveal_text_1 et_animated\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"dsm_block_reveal_text_wrapper\" data-dsm-block-reveal-text=[{\"animation\":\"bt\",\"color\":\"#1B81B4\",\"delay\":\"0.5\",\"viewport\":\"80%\"}]><h2 class=\"dsm_block_reveal_text_header et_pb_module_header\">CARATTERISTICHE SHARPTEK<\/h2><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_row et_pb_row_3 flex-col et_animated et_pb_equal_columns  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_3  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_image et_pb_image_2\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<span class=\"et_pb_image_wrap \"><img decoding=\"async\" width=\"469\" height=\"469\" src=\"https:\/\/www.groupeguillin.fr\/wp-content\/uploads\/2024\/10\/PADLESS-3-1.png\" alt=\"\" title=\"PADLESS-3\" class=\"wp-image-18837\" \/><\/span>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_2  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h3>Design senza pad<\/h3>\n<p class=\"p1\" style=\"text-transform: uppercase;\">un design innovativo che elimina la necessit\u00e0 di colla e di un pad assorbente, <span>RIMUOVENDO<\/span>\u00a0centinaia di tonnellate di imballaggi dalla filiera.<\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_row et_pb_row_4 flex-col et_animated et_pb_equal_columns  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_4  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_3  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h3>Protegge i piccoli frutti delicati<\/h3>\n<p class=\"p1\" style=\"text-transform: uppercase;\">Tecnologia che ammortizza e protegge i frutti morbidi, prevenendo ammaccature e danni.<\/p><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_image et_pb_image_3\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<span class=\"et_pb_image_wrap \"><img decoding=\"async\" width=\"469\" height=\"469\" src=\"https:\/\/www.groupeguillin.fr\/wp-content\/uploads\/2024\/10\/PROTECTION-2-1.png\" alt=\"\" title=\"PROTECTION-2\" class=\"wp-image-18844\" \/><\/span>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_row et_pb_row_5 flex-col et_animated et_pb_equal_columns  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_5  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_image et_pb_image_4\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<span class=\"et_pb_image_wrap \"><img decoding=\"async\" width=\"469\" height=\"469\" src=\"https:\/\/www.groupeguillin.fr\/wp-content\/uploads\/2024\/10\/FOOD-WASTE-REDUCTION-2-1.png\" alt=\"\" title=\"FOOD-WASTE-REDUCTION-2\" class=\"wp-image-18851\" \/><\/span>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_4  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h3>Riduzione degli sprechi alimentari<\/h3>\n<p class=\"p1\" style=\"text-transform: uppercase;\">Tiene i succhi lontani dalla frutta, contribuendo a mantenere la qualit\u00e0 del prodotto e la sua durata.<\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_row et_pb_row_6 flex-col et_animated et_pb_equal_columns  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_6  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_5  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h3>Scorre con facilit\u00e0<\/h3>\n<p class=\"p1\" style=\"text-transform: uppercase;\">Progettato per operare alle velocit\u00e0 attuali delle linee dei clienti senza necessit\u00e0 di costose modifiche.<\/p><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_image et_pb_image_5\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<span class=\"et_pb_image_wrap \"><img decoding=\"async\" width=\"469\" height=\"469\" src=\"https:\/\/www.groupeguillin.fr\/wp-content\/uploads\/2024\/10\/RUNS-WITH-EASE-1.png\" alt=\"\" title=\"RUNS-WITH-EASE\" class=\"wp-image-18858\" \/><\/span>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_row et_pb_row_7 et_pb_equal_columns  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_7  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_button_module_wrapper et_pb_button_0_wrapper et_pb_button_alignment_center et_pb_module \">\n\t\t\t\t<a class=\"et_pb_button et_d4_element et_pb_button_0 et_animated et_pb_bg_layout_light et_block_module\" href=\"http:\/\/www.groupeguillin.fr\/it\/richiesta-di-informazioni-sharptek\/\" data-icon=\"\ue076\">CONTATTACI<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_bottom_inside_divider et-no-transition\"><\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_section et_pb_section_2  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_8 et_animated et_pb_equal_columns  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_8  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_6 et_animated  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><div style=\"text-align: center;\">\n<div class=\"green-underline\" style=\"text-align: center;\"><img decoding=\"async\" src=\"https:\/\/www.groupeguillin.fr\/wp-content\/uploads\/2024\/10\/royaume-uni.png\" width=\"42\" alt=\"\" class=\"wp-image-17214 alignnone size-full\" style=\"display: block; margin-left: auto; margin-right: auto;\" \/>Prodotto nel Regno Unito<\/div>\n<\/div><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_7  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h3 style=\"text-align: center; color: #1b81b4;\">Sviluppato presso l'avanzatissimo stabilimento di produzione di SHARPAK ad Aylesham, che ha recentemente ottenuto una prestigiosa certificazione BRCGS AA+.<\/h3><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_row et_pb_row_9 et_pb_equal_columns  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_1_5 et_pb_column et_pb_column_9  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_image et_pb_image_6\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<span class=\"et_pb_image_wrap \"><img decoding=\"async\" width=\"236\" height=\"165\" src=\"https:\/\/www.groupeguillin.fr\/wp-content\/uploads\/2024\/10\/recoup.jpg\" alt=\"\" title=\"recoup\" class=\"wp-image-18872\" \/><\/span>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_5 et_pb_column et_pb_column_10  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_image et_pb_image_7\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<span class=\"et_pb_image_wrap \"><img decoding=\"async\" width=\"241\" height=\"141\" src=\"https:\/\/www.groupeguillin.fr\/wp-content\/uploads\/2024\/10\/oprl.jpg\" alt=\"\" title=\"oprl\" class=\"wp-image-18879\" \/><\/span>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_5 et_pb_column et_pb_column_11  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_image et_pb_image_8\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<span class=\"et_pb_image_wrap \"><img decoding=\"async\" width=\"230\" height=\"161\" src=\"https:\/\/www.groupeguillin.fr\/wp-content\/uploads\/2024\/10\/bros.jpg\" alt=\"\" title=\"bros\" class=\"wp-image-18886\" \/><\/span>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_5 et_pb_column et_pb_column_12  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_image et_pb_image_9\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<span class=\"et_pb_image_wrap \"><img decoding=\"async\" width=\"221\" height=\"125\" src=\"https:\/\/www.groupeguillin.fr\/wp-content\/uploads\/2024\/10\/uk-pp.jpg\" alt=\"\" title=\"uk pp\" class=\"wp-image-18893\" \/><\/span>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_5 et_pb_column et_pb_column_13  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_image et_pb_image_10\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<span class=\"et_pb_image_wrap \"><img decoding=\"async\" width=\"156\" height=\"215\" src=\"https:\/\/www.groupeguillin.fr\/wp-content\/uploads\/2024\/10\/recycle.jpg\" alt=\"\" title=\"recycle\" class=\"wp-image-18900\" \/><\/span>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_section et_pb_section_3 et_pb_section_parallax et_pb_with_background  et_pb_css_mix_blend_mode et_section_regular section_has_divider et_pb_bottom_divider et_pb_top_divider et_block_section\" >\n\t\t\t\t<div class=\"et_pb_top_inside_divider et-no-transition\"><\/div>\n\t\t\t\t<span class=\"et_parallax_bg_wrap et-pb-parallax-wrapper\"><span\n\t\t\t\t\t\tclass=\"et_parallax_bg et_parallax_bg_phone et_parallax_bg_phone--et_pb_section_3\"\n\t\t\t\t\t\tstyle=\"background-image: url(https:\/\/www.groupeguillin.fr\/wp-content\/uploads\/2024\/10\/RECTO-SHARPTEK-HD-RVB-300dpi.jpg);\"\n\t\t\t\t\t><\/span><\/span><span class=\"et_parallax_bg_wrap et-pb-parallax-wrapper\"><span\n\t\t\t\t\t\tclass=\"et_parallax_bg_phone_exist et_parallax_bg et_parallax_bg_tablet et_parallax_bg_tablet--et_pb_section_3\"\n\t\t\t\t\t\tstyle=\"background-image: url(https:\/\/www.groupeguillin.fr\/wp-content\/uploads\/2024\/10\/RECTO-SHARPTEK-HD-RVB-300dpi.jpg);\"\n\t\t\t\t\t><\/span><\/span>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_bottom_inside_divider et-no-transition\"><\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_section et_pb_section_4 et_pb_with_background  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_10 et_pb_equal_columns et_pb_gutters1  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_14  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element dsm_block_reveal_text dsm_block_reveal_text_2\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"dsm_block_reveal_text_wrapper\" data-dsm-block-reveal-text=[{\"animation\":\"lr\",\"color\":\"#FFFFFF\",\"delay\":\"1\",\"viewport\":\"80%\"}]><h2 class=\"dsm_block_reveal_text_header et_pb_module_header\">SHARPTEK E LA SOSTENIBILIT\u00c1<\/h2><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_divider_0 et_pb_space et_pb_divider_hidden\"><div class=\"et_pb_divider_internal\"><\/div><\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_8 et_animated  et_pb_text_align_center et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h3 style=\"color: #ffffff; line-height: 32px; text-align: center;\">La tecnologia SharpTek non solo semplifica il processo di riciclaggio, ma rimuove anche centinaia di tonnellate di materiali difficili da riciclare dalla filiera, rafforzando il nostro impegno verso la sostenibilit\u00e0.<\/h3><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_divider_1 et_pb_space et_pb_divider_hidden\"><div class=\"et_pb_divider_internal\"><\/div><\/div><div class=\"et_pb_module et_d4_element et_pb_icon et_pb_icon_0 et_animated et-waypoint\">\n\t\t\t\t<span class=\"et_pb_icon_wrap \"><span class=\"et-pb-icon\">\uf078<\/span><\/span>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_row et_pb_row_11 flex-col et_animated et_pb_equal_columns  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_15  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_9  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h3>Completamente riciclabile<\/h3>\n<p class=\"p1\" style=\"text-transform: uppercase;\">Soluzione di imballaggio in PET monomateriale raccolto alla fonte per un facile riciclaggio.<\/p><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_image et_pb_image_11\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<span class=\"et_pb_image_wrap \"><img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.groupeguillin.fr\/wp-content\/uploads\/2024\/10\/picto-fully-recyclable.png\" alt=\"\" title=\"picto-fully-recyclable\" class=\"wp-image-18914\" \/><\/span>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_row et_pb_row_12 flex-col et_animated et_pb_equal_columns  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_16  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_image et_pb_image_12\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<span class=\"et_pb_image_wrap \"><img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.groupeguillin.fr\/wp-content\/uploads\/2024\/10\/picto-unit-reduction.png\" alt=\"\" title=\"picto-unit-reduction\" class=\"wp-image-18921\" \/><\/span>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_10  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h3>Riduzione del numero di unit\u00e0 di imballaggio<\/h3>\n<p class=\"p1\" style=\"text-transform: uppercase;\">Niente pad, meno imballaggio!<\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_row et_pb_row_13 flex-col et_animated et_pb_equal_columns  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_17  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_11  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h3>Riduzione del peso dell'Imballaggio<\/h3>\n<p class=\"p1\" style=\"text-transform: uppercase;\">17% pi\u00f9 leggero grazie alla tecnologia SharpTek rispetto all'attuale vassoio equivalente con pad assorbente.<\/p><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_image et_pb_image_13\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<span class=\"et_pb_image_wrap \"><img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.groupeguillin.fr\/wp-content\/uploads\/2024\/10\/picto-weight-reduction.png\" alt=\"\" title=\"picto-weight-reduction\" class=\"wp-image-18928\" \/><\/span>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_row et_pb_row_14 flex-col et_animated et_pb_equal_columns  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_18  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_image et_pb_image_14\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<span class=\"et_pb_image_wrap \"><img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.groupeguillin.fr\/wp-content\/uploads\/2024\/10\/picto-circular-economy.png\" alt=\"\" title=\"picto-circular-economy\" class=\"wp-image-18935\" \/><\/span>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_12  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h3>Economia circolare<\/h3>\n<p class=\"p1\" style=\"text-transform: uppercase;\">La tecnologia SharpTek \u00e8 utilizzata nei vassoi per piccoli frutti delicati, incorporando fino all'80% di PET riciclato (RPET).<\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_row et_pb_row_15 et_pb_equal_columns  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_19  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_button_module_wrapper et_pb_button_1_wrapper et_pb_button_alignment_center et_pb_module \">\n\t\t\t\t<a class=\"et_pb_button et_d4_element et_pb_button_1 et_animated et_pb_bg_layout_light et_block_module\" href=\"http:\/\/www.groupeguillin.fr\/it\/richiesta-di-informazioni-sharptek\/\" data-icon=\"\ue076\">CONTATTACI<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-19256","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sharptek - Groupe GUILLIN<\/title>\n<meta name=\"description\" content=\"Le Groupe GUILLIN est le r\u00e9f\u00e9rent europ\u00e9en de l&#039;emballage plastique alimentaire\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.groupeguillin.fr\/it\/sharptek\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sharptek - Groupe GUILLIN\" \/>\n<meta property=\"og:description\" content=\"Le Groupe GUILLIN est le r\u00e9f\u00e9rent europ\u00e9en de l&#039;emballage plastique alimentaire\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.groupeguillin.fr\/it\/sharptek\/\" \/>\n<meta property=\"og:site_name\" content=\"Groupe GUILLIN\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-25T15:31:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.groupeguillin.fr\/wp-content\/uploads\/2024\/10\/royaume-uni.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.groupeguillin.fr\\\/it\\\/sharptek\\\/\",\"url\":\"https:\\\/\\\/www.groupeguillin.fr\\\/it\\\/sharptek\\\/\",\"name\":\"Sharptek - Groupe GUILLIN\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.groupeguillin.fr\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.groupeguillin.fr\\\/it\\\/sharptek\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.groupeguillin.fr\\\/it\\\/sharptek\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.groupeguillin.fr\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/royaume-uni.png\",\"datePublished\":\"2024-11-15T16:24:44+00:00\",\"dateModified\":\"2025-06-25T15:31:24+00:00\",\"description\":\"Le Groupe GUILLIN est le r\u00e9f\u00e9rent europ\u00e9en de l'emballage plastique alimentaire\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.groupeguillin.fr\\\/it\\\/sharptek\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.groupeguillin.fr\\\/it\\\/sharptek\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.groupeguillin.fr\\\/it\\\/sharptek\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.groupeguillin.fr\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/royaume-uni.png\",\"contentUrl\":\"https:\\\/\\\/www.groupeguillin.fr\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/royaume-uni.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.groupeguillin.fr\\\/it\\\/sharptek\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.groupeguillin.fr\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sharptek\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.groupeguillin.fr\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.groupeguillin.fr\\\/it\\\/\",\"name\":\"Groupe GUILLIN\",\"description\":\"We protect your food\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.groupeguillin.fr\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.groupeguillin.fr\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.groupeguillin.fr\\\/it\\\/#organization\",\"name\":\"Groupe GUILLIN\",\"url\":\"https:\\\/\\\/www.groupeguillin.fr\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.groupeguillin.fr\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.groupeguillin.fr\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Logo-guillin-1.png\",\"contentUrl\":\"https:\\\/\\\/www.groupeguillin.fr\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Logo-guillin-1.png\",\"width\":1172,\"height\":300,\"caption\":\"Groupe GUILLIN\"},\"image\":{\"@id\":\"https:\\\/\\\/www.groupeguillin.fr\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/groupeguillin\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/guillin-emballages\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCS-Q4Qkgd1bN9pdIPGRjogQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sharptek - Groupe GUILLIN","description":"Le Groupe GUILLIN est le r\u00e9f\u00e9rent europ\u00e9en de l'emballage plastique alimentaire","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.groupeguillin.fr\/it\/sharptek\/","og_locale":"it_IT","og_type":"article","og_title":"Sharptek - Groupe GUILLIN","og_description":"Le Groupe GUILLIN est le r\u00e9f\u00e9rent europ\u00e9en de l'emballage plastique alimentaire","og_url":"https:\/\/www.groupeguillin.fr\/it\/sharptek\/","og_site_name":"Groupe GUILLIN","article_modified_time":"2025-06-25T15:31:24+00:00","og_image":[{"url":"https:\/\/www.groupeguillin.fr\/wp-content\/uploads\/2024\/10\/royaume-uni.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.groupeguillin.fr\/it\/sharptek\/","url":"https:\/\/www.groupeguillin.fr\/it\/sharptek\/","name":"Sharptek - Groupe GUILLIN","isPartOf":{"@id":"https:\/\/www.groupeguillin.fr\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.groupeguillin.fr\/it\/sharptek\/#primaryimage"},"image":{"@id":"https:\/\/www.groupeguillin.fr\/it\/sharptek\/#primaryimage"},"thumbnailUrl":"https:\/\/www.groupeguillin.fr\/wp-content\/uploads\/2024\/10\/royaume-uni.png","datePublished":"2024-11-15T16:24:44+00:00","dateModified":"2025-06-25T15:31:24+00:00","description":"Le Groupe GUILLIN est le r\u00e9f\u00e9rent europ\u00e9en de l'emballage plastique alimentaire","breadcrumb":{"@id":"https:\/\/www.groupeguillin.fr\/it\/sharptek\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.groupeguillin.fr\/it\/sharptek\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.groupeguillin.fr\/it\/sharptek\/#primaryimage","url":"https:\/\/www.groupeguillin.fr\/wp-content\/uploads\/2024\/10\/royaume-uni.png","contentUrl":"https:\/\/www.groupeguillin.fr\/wp-content\/uploads\/2024\/10\/royaume-uni.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.groupeguillin.fr\/it\/sharptek\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.groupeguillin.fr\/it\/"},{"@type":"ListItem","position":2,"name":"Sharptek"}]},{"@type":"WebSite","@id":"https:\/\/www.groupeguillin.fr\/it\/#website","url":"https:\/\/www.groupeguillin.fr\/it\/","name":"Groupe GUILLIN","description":"We protect your food","publisher":{"@id":"https:\/\/www.groupeguillin.fr\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.groupeguillin.fr\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.groupeguillin.fr\/it\/#organization","name":"Groupe GUILLIN","url":"https:\/\/www.groupeguillin.fr\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.groupeguillin.fr\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.groupeguillin.fr\/wp-content\/uploads\/2020\/09\/Logo-guillin-1.png","contentUrl":"https:\/\/www.groupeguillin.fr\/wp-content\/uploads\/2020\/09\/Logo-guillin-1.png","width":1172,"height":300,"caption":"Groupe GUILLIN"},"image":{"@id":"https:\/\/www.groupeguillin.fr\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/groupeguillin\/","https:\/\/www.linkedin.com\/company\/guillin-emballages\/","https:\/\/www.youtube.com\/channel\/UCS-Q4Qkgd1bN9pdIPGRjogQ"]}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 11:38:35","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"translation_priority","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.groupeguillin.fr\/it\/wp-json\/wp\/v2\/pages\/19256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.groupeguillin.fr\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.groupeguillin.fr\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.groupeguillin.fr\/it\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.groupeguillin.fr\/it\/wp-json\/wp\/v2\/comments?post=19256"}],"version-history":[{"count":8,"href":"https:\/\/www.groupeguillin.fr\/it\/wp-json\/wp\/v2\/pages\/19256\/revisions"}],"predecessor-version":[{"id":21231,"href":"https:\/\/www.groupeguillin.fr\/it\/wp-json\/wp\/v2\/pages\/19256\/revisions\/21231"}],"wp:attachment":[{"href":"https:\/\/www.groupeguillin.fr\/it\/wp-json\/wp\/v2\/media?parent=19256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}